{"id":6920,"date":"2022-06-10T08:00:00","date_gmt":"2022-06-10T08:00:00","guid":{"rendered":"https:\/\/beneito-faure.com\/noticias\/illuminacio-integrada-carril-magnetic\/"},"modified":"2022-06-10T08:00:00","modified_gmt":"2022-06-10T08:00:00","slug":"illuminacio-integrada-carril-magnetic","status":"publish","type":"post","link":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/","title":{"rendered":"Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram"},"content":{"rendered":"<h2>Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram<\/h2>\n<p>Els nous carrils magn\u00e8tics de 48V de Beneito Faure ofereixen grans acabats i una simplicitat de l\u00ednies que li confereixen una personalitat especial i \u00fanica a l\u2019espai. S\u00f3n una tend\u00e8ncia en il\u00b7luminaci\u00f3 gr\u00e0cies a la seva est\u00e8tica, funcionalitat i versatilitat. A m\u00e9s, ofereixen una integraci\u00f3 de la il\u00b7luminaci\u00f3, ja que el carril es pot instal\u00b7lar encastat.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p>Els models <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/line-2\/\">Line<\/a> i <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/tram-48v-2\/\">Tram<\/a> s\u00f3n els nous focus decoratius que s&#8217;insereixen dins del carril. Al llarg del carril se\u2019n poden col\u00b7locar tants com es vulguin, ja que totes les peces van imantades. Aix\u00f2 permet una mobilitat i flexibilitat completes, sense necessitat d\u2019haver de tenir cables.<\/p>\n<p>Line \u00e9s la nova pe\u00e7a d\u2019il\u00b7luminaci\u00f3 dissenyada per oferir una total llibertat en la creaci\u00f3 de l\u00ednies rectes, angles i fins i tot dissenys d&#8217;il\u00b7luminaci\u00f3 que pugen per la paret i prossegueixen pel sostre. La seva pot\u00e8ncia \u00e9s de 7,5W, 15W i 30W per a les diferents versions de 300mm i 607mm i 1.207mm de llarg. Eleg\u00e0ncia i composici\u00f3 lliure s\u00f3n algunes de les caracter\u00edstiques d&#8217;aquesta pe\u00e7a formada per l\u00ednies rectes i precises. La seva temperatura de color \u00e9s de 3.000K i amb un feix de llum de 100\u00ba, un UGR &lt;19 i un CRI &gt;90, \u00e9s perfecta per a un entorn dom\u00e8stic de disseny minimalista i atrevit.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure2-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Line_Beneito_Faure3-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p>La nova col\u00b7lecci\u00f3 decorativa <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/tram-48v-2\/\">Tram<\/a> tamb\u00e9 ofereix una total personalitzaci\u00f3 que s&#8217;adapta a qualsevol espai, des d&#8217;un menjador, cuina o passad\u00eds. La seva pot\u00e8ncia \u00e9s de 4,5W i 9W per a les diferents versions de 128mm i 210mm de llarg.<\/p>\n<p>Tram s&#8217;insereix dins del carril magn\u00e8tic i genera una pres\u00e8ncia visual composta per diversos punts de llum. Cada pe\u00e7a de la col\u00b7lecci\u00f3 \u00e9s movible dins un carril que es pot executar a mida, aportant aix\u00ed una gran transformaci\u00f3 i adaptaci\u00f3 de la llum en cohesi\u00f3 amb el disseny de l\u2019espai. Tram ofereix una temperatura de color de 2.700K i 3.000K, un feix de llum de 38\u00ba, un UGR &lt;19 i un CRI &gt;90.<\/p>\n<p>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure2-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><br \/>\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1920\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3.jpg\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3.jpg 1080w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-169x300.jpg 169w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-576x1024.jpg 576w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-768x1365.jpg 768w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-864x1536.jpg 864w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-307x545.jpg 307w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-700x1244.jpg 700w, https:\/\/beneito-faure.com\/wp-content\/uploads\/2022\/06\/Tram_Beneito_Faure3-509x905.jpg 509w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/p>\n<p>El carril magn\u00e8tic facilita qualsevol instal\u00b7laci\u00f3 o canvi als punts de llum. A m\u00e9s, en ser un carril imantat, els focus s&#8217;acoblen perfectament de forma senzilla i s&#8217;il\u00b7luminen quan entren en contacte amb el carril. Descobreix l&#8217;\u00e0mplia col\u00b7lecci\u00f3 de peces decoratives d&#8217;alta qualitat per a carrils magn\u00e8tics de 48V <a href=\"https:\/\/beneito-faure.com\/ca\/nova-colleccio-decorativa-per-a-carril-magnetic-de-48v\/\">aqu\u00ed<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[864],"tags":[],"class_list":["post-6920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure<\/title>\n<meta name=\"description\" content=\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure\" \/>\n<meta property=\"og:description\" content=\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/\" \/>\n<meta property=\"og:site_name\" content=\"Beneito Faure\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-10T08:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\"},\"headline\":\"Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram\",\"datePublished\":\"2022-06-10T08:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/\"},\"wordCount\":444,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/Integrated_Lighting_Beneito_Faure-1.webp\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/\",\"url\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/\",\"name\":\"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/Integrated_Lighting_Beneito_Faure-1.webp\",\"datePublished\":\"2022-06-10T08:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\"},\"description\":\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/Integrated_Lighting_Beneito_Faure-1.webp\",\"contentUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/Integrated_Lighting_Beneito_Faure-1.webp\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-integrada-carril-magnetic\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#website\",\"url\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/\",\"name\":\"Beneito Faure\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"sameAs\":[\"https:\\\/\\\/beneito-faure.com\\\/wp\"],\"url\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/","og_locale":"ca_ES","og_type":"article","og_title":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","og_description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","og_url":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/","og_site_name":"Beneito Faure","article_published_time":"2022-06-10T08:00:00+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp","type":"image\/webp"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"mortensen","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#article","isPartOf":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/"},"author":{"name":"mortensen","@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a"},"headline":"Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram","datePublished":"2022-06-10T08:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/"},"wordCount":444,"commentCount":0,"image":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#primaryimage"},"thumbnailUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp","articleSection":["Not\u00edcies"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/","url":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/","name":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","isPartOf":{"@id":"https:\/\/beneitofaure.mortensen.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#primaryimage"},"image":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#primaryimage"},"thumbnailUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp","datePublished":"2022-06-10T08:00:00+00:00","author":{"@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a"},"description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","breadcrumb":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#primaryimage","url":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp","contentUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/Integrated_Lighting_Beneito_Faure-1.webp","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-integrada-carril-magnetic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneito-faure.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Il\u00b7luminaci\u00f3 integrada amb carril magn\u00e8tic: descobreix Line i Tram"}]},{"@type":"WebSite","@id":"https:\/\/beneitofaure.mortensen.cat\/#website","url":"https:\/\/beneitofaure.mortensen.cat\/","name":"Beneito Faure","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneitofaure.mortensen.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","caption":"mortensen"},"sameAs":["https:\/\/beneito-faure.com\/wp"],"url":"https:\/\/beneito-faure.com\/ca\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts\/6920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/comments?post=6920"}],"version-history":[{"count":0,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts\/6920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/media\/6654"}],"wp:attachment":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/media?parent=6920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/categories?post=6920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/tags?post=6920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}