{"id":6901,"date":"2021-08-20T04:49:14","date_gmt":"2021-08-20T04:49:14","guid":{"rendered":"https:\/\/beneito-faure.com\/noticias\/illuminacio-portatil-per-a-exteriors\/"},"modified":"2021-08-20T04:49:14","modified_gmt":"2021-08-20T04:49:14","slug":"illuminacio-portatil-per-a-exteriors","status":"publish","type":"post","link":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/","title":{"rendered":"Il\u00b7luminaci\u00f3 port\u00e0til per a exteriors"},"content":{"rendered":"<h2>Com aconseguir que el teu exterior brilli amb llum propia<\/h2>\n<p>Les terrasses, els balcons i els espais oberts s\u00f3n els grans aliats del bon temps, la calor, i els sopars en companyia. Els llums port\u00e0tils s\u00f3n ideals per treure-li profit al teu exterior i que brilli amb llum pr\u00f2pia. Permeten crear diferents ambients, canviar-les de lloc lliurement i aporten un element decoratiu.<\/p>\n<p>A Beneito Faure som experts en il\u00b7luminaci\u00f3 LED i portem anys treballant amb una \u00e0mplia gamma de productes per a la il\u00b7luminaci\u00f3 exterior. I cal remarcar que la il\u00b7luminaci\u00f3 mai havia estat m\u00e9s intel\u00b7ligent. En aquest article parlarem de diferents opcions port\u00e0tils id\u00f2nies per a la il\u00b7luminaci\u00f3 puntual tant als interiors de restaurants i terrasses com a habitatges. A m\u00e9s, no han d&#8217;estar connectades al corrent perqu\u00e8 compten amb bateries potents capaces d&#8217;enllumenar durant hores. Amb la col\u00b7lecci\u00f3 de l\u00e0mpades port\u00e0tils amb bateria, la llum no ser\u00e0 una excusa per no gaudir de la teva terrassa o balc\u00f3.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" style=\"font-size: 1rem; caret-color: #000000; color: #000000;\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2021\/08\/blog1.jpg\" alt=\"\" width=\"1920\" height=\"1080\" \/><\/p>\n<p>Per un costat tenim el model <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/visor-2\/\">Visor<\/a> amb 5W de pot\u00e8ncia disponible amb acabats en blanc i corten. Gr\u00e0cies a la nansa a la part superior i el lleuger pes, el producte \u00e9s f\u00e0cilment transportable.<\/p>\n<p>El mateix passa amb el model <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/visor-solar-2\/\">Visor Solar<\/a>, que a part de suposar un estalvi energ\u00e8tic, pot ser col\u00b7locada com a element decoratiu, o punt de llum per a una zona chill-out.<\/p>\n<p>El model <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/converse-2\/?item=converse-lighting-25w-2\" target=\"_blank\" rel=\"noopener\">Converse Lighting<\/a> \u00e9s un dels m\u00e9s representatius de la nostra firma. Compte amb un sensor gravitatori que genera dues tonalitats de color (2700K i 5000K), segons la posici\u00f3 del llum. Disposa duna bateria de liti amb fins a 180 hores dautonomia i una rec\u00e0rrega micro USB del dispositiu en menys de 4 hores.<\/p>\n<p>Si el que busquem \u00e9s una il\u00b7luminaci\u00f3 per a una taula auxiliar tenim l&#8217;opci\u00f3 <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/trion-2\/\">Trion<\/a>, que projecta llum a 360 \u00ba. Compte amb un control t\u00e0ctil d&#8217;encesa, apagat i regulaci\u00f3 d&#8217;intensitat. Amb un sol clic pots canviar la temperatura lum\u00ednica de 3000K a 4000K.<\/p>\n<p>Finalment, amb un disseny contemporani i minimalista, tenim el nou llum <a href=\"https:\/\/beneito-faure.com\/ca\/productos\/lievo\/\">Lievo<\/a>, un llum sense cables amb un disseny avantguardista. Disposa d&#8217;un bot\u00f3 t\u00e0ctil tipus &#8216;touch control&#8217; a la part superior per encendre, apagar o controlar la intensitat de llum. Al mateix temps es converteix tamb\u00e9 en un element de decoraci\u00f3 que omplir\u00e0 d&#8217;estil l&#8217;espai on la situem.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/beneito-faure.com\/wp-content\/uploads\/2021\/08\/blog2.jpg\" alt=\"\" width=\"1920\" height=\"1080\" \/><\/p>\n<p>Aquestes solucions lum\u00edniques encaixen tant en terrasses grans com a balcons petits o interiors, tenint en compte el factor ambiental. Tecnologia i disseny de la m\u00e0 per crear espais acollidors, plens de llum i vida.<\/p>\n<p style=\"margin: 0cm; font-size: medium; font-family: 'Times New Roman', serif; caret-color: #000000; color: #000000; font-style: normal;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":6615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[864],"tags":[],"class_list":["post-6901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticies"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure<\/title>\n<meta name=\"description\" content=\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure\" \/>\n<meta property=\"og:description\" content=\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/\" \/>\n<meta property=\"og:site_name\" content=\"Beneito Faure\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-20T04:49:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"mortensen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"mortensen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/\"},\"author\":{\"name\":\"mortensen\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\"},\"headline\":\"Il\u00b7luminaci\u00f3 port\u00e0til per a exteriors\",\"datePublished\":\"2021-08-20T04:49:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/\"},\"wordCount\":458,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/portada-blog-3.webp\",\"articleSection\":[\"Not\u00edcies\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/\",\"url\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/\",\"name\":\"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/portada-blog-3.webp\",\"datePublished\":\"2021-08-20T04:49:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\"},\"description\":\"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/portada-blog-3.webp\",\"contentUrl\":\"https:\\\/\\\/beneito-faure.com\\\/app\\\/uploads\\\/2026\\\/06\\\/portada-blog-3.webp\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/noticies\\\/illuminacio-portatil-per-a-exteriors\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il\u00b7luminaci\u00f3 port\u00e0til per a exteriors\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#website\",\"url\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/\",\"name\":\"Beneito Faure\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beneitofaure.mortensen.cat\\\/#\\\/schema\\\/person\\\/6f6e0b6dafa38d8e4f4a8cd26ed3189a\",\"name\":\"mortensen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g\",\"caption\":\"mortensen\"},\"sameAs\":[\"https:\\\/\\\/beneito-faure.com\\\/wp\"],\"url\":\"https:\\\/\\\/beneito-faure.com\\\/ca\\\/author\\\/mortensen\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/","og_locale":"ca_ES","og_type":"article","og_title":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","og_description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","og_url":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/","og_site_name":"Beneito Faure","article_published_time":"2021-08-20T04:49:14+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp","type":"image\/webp"}],"author":"mortensen","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"mortensen","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#article","isPartOf":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/"},"author":{"name":"mortensen","@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a"},"headline":"Il\u00b7luminaci\u00f3 port\u00e0til per a exteriors","datePublished":"2021-08-20T04:49:14+00:00","mainEntityOfPage":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/"},"wordCount":458,"commentCount":0,"image":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#primaryimage"},"thumbnailUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp","articleSection":["Not\u00edcies"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/","url":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/","name":"Actualidad en iluminaci\u00f3n LED y proyectos | Beneito Faure","isPartOf":{"@id":"https:\/\/beneitofaure.mortensen.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#primaryimage"},"image":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#primaryimage"},"thumbnailUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp","datePublished":"2021-08-20T04:49:14+00:00","author":{"@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a"},"description":"Descubre la actualidad de Beneito Faure: proyectos, innovaci\u00f3n y tendencias en iluminaci\u00f3n LED para arquitectura y espacios profesionales.","breadcrumb":{"@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#primaryimage","url":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp","contentUrl":"https:\/\/beneito-faure.com\/app\/uploads\/2026\/06\/portada-blog-3.webp","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/beneito-faure.com\/ca\/noticies\/illuminacio-portatil-per-a-exteriors\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/beneito-faure.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Il\u00b7luminaci\u00f3 port\u00e0til per a exteriors"}]},{"@type":"WebSite","@id":"https:\/\/beneitofaure.mortensen.cat\/#website","url":"https:\/\/beneitofaure.mortensen.cat\/","name":"Beneito Faure","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beneitofaure.mortensen.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/beneitofaure.mortensen.cat\/#\/schema\/person\/6f6e0b6dafa38d8e4f4a8cd26ed3189a","name":"mortensen","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6e79aaf705e1efb28fda44f2641ffc89246ccd7a0374a816708380f7c3a34212?s=96&d=mm&r=g","caption":"mortensen"},"sameAs":["https:\/\/beneito-faure.com\/wp"],"url":"https:\/\/beneito-faure.com\/ca\/author\/mortensen\/"}]}},"_links":{"self":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts\/6901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/comments?post=6901"}],"version-history":[{"count":0,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/posts\/6901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/media\/6615"}],"wp:attachment":[{"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/media?parent=6901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/categories?post=6901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beneito-faure.com\/ca\/wp-json\/wp\/v2\/tags?post=6901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}